{"id":44774,"date":"2022-04-21T06:38:47","date_gmt":"2022-04-21T09:38:47","guid":{"rendered":"https:\/\/marituba.pa.gov.br\/site\/?p=44774"},"modified":"2022-04-21T06:38:47","modified_gmt":"2022-04-21T09:38:47","slug":"marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico","status":"publish","type":"post","link":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/","title":{"rendered":"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico"},"content":{"rendered":"<p>Hoje, 21 de abril, Marituba completa 28 anos de emancipa\u00e7\u00e3o pol\u00edtica. Nascida dentro do processo de ocupa\u00e7\u00e3o e de desenvolvimento da regi\u00e3o Amaz\u00f4nica, o munic\u00edpio mant\u00e9m sua tradi\u00e7\u00e3o derivada do amor de seus moradores e vis\u00e3o empreendedora dos diferentes povos que formaram a popula\u00e7\u00e3o do munic\u00edpio.<\/p>\n<figure id=\"attachment_44567\" aria-describedby=\"caption-attachment-44567\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Restauracao-Caixa-Dagua-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-44567 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Restauracao-Caixa-Dagua-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><figcaption id=\"caption-attachment-44567\" class=\"wp-caption-text\">A caixa d&#8217;\u00e1gua que serviu para o abastecimento dos trens da Ferrovia Bel\u00e9m\/Bragan\u00e7a.<\/figcaption><\/figure>\n<p>O povoado de Marituba tem origem na Vila Oper\u00e1ria, constru\u00edda na d\u00e9cada de 1900 para abrigar os oper\u00e1rios de manuten\u00e7\u00e3o das oficinas dos trens e demais funcion\u00e1rios da Estrada de Ferro Bel\u00e9m\/Bragan\u00e7a.<\/p>\n<p>At\u00e9 meados da d\u00e9cada de 1940 a economia local era pautada nas atividades comerciais de apoio \u00e0 ferrovia e numa incipiente agricultura de subsist\u00eancia. A efetiva expans\u00e3o da vila \u00e9 consequ\u00eancia da chegada dos primeiros comerciantes, cujos empreendimentos contribu\u00edram para a conforma\u00e7\u00e3o do n\u00facleo urbano de Marituba.<\/p>\n<p>A ocupa\u00e7\u00e3o de Marituba se iniciou pelo bairro Centro originado da povoa\u00e7\u00e3o consequente da ocupa\u00e7\u00e3o por parte dos oper\u00e1rios que trabalhavam na constru\u00e7\u00e3o e na opera\u00e7\u00e3o da ferrovia.<\/p>\n<p>A rotina da vida no bairro mais antigo de Marituba ainda persiste na mem\u00f3ria dos primeiros moradores. Como no caso da pensionista Ingrid Bergman Cromwell, de 68 anos. Ela mora h\u00e1 40 anos no bairro Centro e tem no local a sua refer\u00eancia de vida.<\/p>\n<p>Os primeiros contatos com o bairro foram atrav\u00e9s de seu pai que tinha alguns amigos que trabalhavam na ferrovia. Dos primeiros anos, ela se recorda de um terreno que o seu pai comprou onde criava carneiros e outros animais.<\/p>\n<figure id=\"attachment_43966\" aria-describedby=\"caption-attachment-43966\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-13.54.30.jpeg\"><img decoding=\"async\" class=\"wp-image-43966 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-13.54.30-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-13.54.30-300x200.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-13.54.30-1024x683.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-13.54.30-1536x1024.jpeg 1536w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-08-at-13.54.30.jpeg 1599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-43966\" class=\"wp-caption-text\">Ingrid Bergman, 68 anos, mora h\u00e1 40 anos no Centro.<\/figcaption><\/figure>\n<p>\u201cN\u00f3s mor\u00e1vamos em Bel\u00e9m, mas v\u00ednhamos para c\u00e1 frequentar o Igarap\u00e9 da Mata que era a coisa mais linda do mundo. Meu pai se apaixonou pelo local e logo compramos uma casa de madeira. Viemos morar em Marituba e frequent\u00e1vamos a antiga Prainha. Inicialmente somente n\u00f3s e alguns oper\u00e1rios da Estrada de Ferro frequent\u00e1vamos o local\u201d, conta.<\/p>\n<p><strong>A emancipa\u00e7\u00e3o<\/strong> &#8211; A eleva\u00e7\u00e3o de Marituba \u00e0 categoria de munic\u00edpio refletiu o anseio da popula\u00e7\u00e3o, que desde 1983 buscava a autonomia da vila. Foram tr\u00eas movimentos emancipacionistas: o primeiro, em 1983; o segundo, em 1991; e o \u00faltimo, em 1993.<\/p>\n<figure id=\"attachment_44785\" aria-describedby=\"caption-attachment-44785\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/foto-emancipacao.jpeg\"><img decoding=\"async\" class=\"wp-image-44785 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/foto-emancipacao-300x183.jpeg\" alt=\"\" width=\"300\" height=\"183\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/foto-emancipacao-300x183.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/foto-emancipacao.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44785\" class=\"wp-caption-text\">O plebiscito que deu referendo a emancipa\u00e7\u00e3o pol\u00edtica de Marituba.<\/figcaption><\/figure>\n<p>\u00c0 frente do terceiro movimento de emancipa\u00e7\u00e3o, que culminou com a autonomia de Marituba, estavam Fernando Corr\u00eaa e El\u00e1dio Soares. O primeiro tamb\u00e9m foi eleito como primeiro prefeito do munic\u00edpio. O segundo, falecido em 2008, d\u00e1 nome \u00e0 Unidade de Pronto Atendimento (UPA), de Marituba.<\/p>\n<p>O servidor p\u00fablico Ivan Soares, 65 anos, \u00e9 filho de El\u00e1dio Soares. Ele acompanhou todo o processo de emancipa\u00e7\u00e3o ao lado do pai e conta que o descontentamento com a situa\u00e7\u00e3o do munic\u00edpio, que fazia parte de Benevides, motivou o grupo a iniciar o movimento, ap\u00f3s duas tentativas anteriores frustradas.<\/p>\n<figure id=\"attachment_44817\" aria-describedby=\"caption-attachment-44817\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/ivan.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44817 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/ivan-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/ivan-300x200.jpg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/ivan-1024x681.jpg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/ivan-1536x1022.jpg 1536w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/ivan-2048x1362.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44817\" class=\"wp-caption-text\">Ivan Soares \u00e9 filho de El\u00e1dio Soares, um dos personagens principais da luta pela emancipa\u00e7\u00e3o.<\/figcaption><\/figure>\n<p>Ivan lembra que o pai, El\u00e1dio Soares, era corretor de im\u00f3veis e fazia parte de um grupo que se demonstrava insatisfeito com o fato do ent\u00e3o distrito ser relegado a segundo plano e, juntos, os membros desse grupo come\u00e7aram, ent\u00e3o, a discutir uma forma de emancip\u00e1-lo. Do grupo faziam parte pol\u00edticos, empres\u00e1rios, jornalistas, universit\u00e1rios e lideran\u00e7as religiosas, entre outras, que passaram a se reunir na Par\u00f3quia do Menino Deus.<\/p>\n<p>Em 1993, um outdoor em frente \u00e0 feira de Marituba, conclamando a popula\u00e7\u00e3o a engajar-se na luta em prol da emancipa\u00e7\u00e3o teve grande repercuss\u00e3o, dando in\u00edcio a forma\u00e7\u00e3o da Comiss\u00e3o Pr\u00f3-Emancipa\u00e7\u00e3o de Marituba (Copem), liderada primeiramente por Fernando Corr\u00eaa e, mais tarde, por El\u00e1dio Soares.<\/p>\n<p>Em 1994, pela Lei Estadual N\u00ba 5.857\/1994, a ent\u00e3o localidade de Marituba \u00e9 elevada \u00e0 categoria de munic\u00edpio, com \u00e1rea desmembrada do munic\u00edpio de Benevides. Constitu\u00eddo do distrito administrativo sede, o munic\u00edpio de Marituba foi oficialmente instalado em 1997.<\/p>\n<figure id=\"attachment_44818\" aria-describedby=\"caption-attachment-44818\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/colonia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44818 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/colonia-300x168.png\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/colonia-300x168.png 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/colonia.png 916w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44818\" class=\"wp-caption-text\">A Col\u00f4nia de Marituba foi um elemento formador da popula\u00e7\u00e3o de Marituba.<\/figcaption><\/figure>\n<p><strong>A Col\u00f4nia de Marituba e o bairro Dom Aristides<\/strong> &#8211; De acordo com as estimativas populacionais do IBGE, atualmente Marituba possui cerca de 129 mil habitantes em 20 bairros. Um deles, o Dom Aristides, nasceu da antiga cidade hospital, a Col\u00f4nia de Marituba que foi constru\u00edda, em Marituba, na Era Get\u00falio Vargas, no per\u00edodo de 1930, quando foram fomentadas as constru\u00e7\u00f5es de asilos-hospitais que abrigariam os infectados pela ent\u00e3o denominada lepra.<\/p>\n<p>Em 1942 o lepros\u00e1rio de Marituba foi inaugurado com pavilh\u00f5es que apresentariam em torno de 28 leitos, cada um com 14 quartos com portas externas e sem janelas.<\/p>\n<p>Em 1976, a nova pol\u00edtica de sa\u00fade estabeleceu que portadores de hansen\u00edase n\u00e3o poderiam ser mais segregados e sim, tratados e inseridos em seu meio social. Com isso, as col\u00f4nias em todo o Brasil deveriam ser transformadas em hospitais e asilos. Mas, em Marituba, o processo s\u00f3 teve final em 1986 ap\u00f3s a visita de Jo\u00e3o Paulo II que fez o pedido ao Governo para quebrar a corrente das col\u00f4nias (fato que remete \u00e0s grossas correntes que ficavam na entrada da Col\u00f4nia que hoje se chama avenida Jo\u00e3o Paulo II.<\/p>\n<p>Nesta mesma \u00e9poca o governador Almir Gabriel revitalizou as col\u00f4nias no Estado do Par\u00e1. A partir da\u00ed as pessoas passaram a n\u00e3o estar mais segregadas, por\u00e9m continuaram dentro da col\u00f4nia. Muitos constitu\u00edram fam\u00edlias. Outros foram abandonados pela fam\u00edlia e n\u00e3o tinham mais para onde ir.<\/p>\n<p>Hoje ainda existem cerca de 200 pacientes que permanecem na estrutura do que era a col\u00f4nia. Muitos venderam suas propriedades, alguns ampliaram suas casas e mantiveram a estrutura original. As estruturas que constitu\u00edram a antiga Col\u00f4nia de Marituba ainda permanecem pelos mais de 300 hectares, at\u00e9 a rodovia BR 316 onde ficavam as correntes que separavam a col\u00f4nia da sociedade.<\/p>\n<figure id=\"attachment_44819\" aria-describedby=\"caption-attachment-44819\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Edmilson.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44819 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Edmilson-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Edmilson-300x200.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Edmilson-1024x683.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Edmilson-1536x1024.jpeg 1536w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/Edmilson.jpeg 1599w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44819\" class=\"wp-caption-text\">Edmilson Pican\u00e7o, lideran\u00e7a de Marituba, legado da forma\u00e7\u00e3o populacional consequente da Col\u00f4nia de Marituba.<\/figcaption><\/figure>\n<p>Assim se forma o bairro que hoje se chama Dom Aristides. O nome \u00e9 uma homenagem a Aristides Pirovano, nascido na It\u00e1lia, bispo cat\u00f3lico, membro do Pontif\u00edcio Instituto para as Miss\u00f5es Estrangeiras e que foi Capel\u00e3o Auxiliar na Col\u00f4nia de Hansenianos de Marituba, desde 1978 e falecido em 1997, em sua terra natal. Ele \u00e9 considerado pai benfeitor dos hansenianos e atribuem a ele a visita do Papa Jo\u00e3o Paulo II na col\u00f4nia.<\/p>\n<p>Edmilson Pican\u00e7o, 48 anos, \u00e9 coordenador em Marituba do Movimento de Reintegra\u00e7\u00e3o das Pessoas Atingidas pela Hansen\u00edase (Morhan), uma entidade sem fins lucrativos fundada em 6 de Junho de 1981. A luta de Edmilson Pican\u00e7o pela causa vem de sua hist\u00f3ria. Filho de hansenianos, ele foi separado de seus pais ainda rec\u00e9m-nascido e somente retornou para a fam\u00edlia aos oito anos de idade.<\/p>\n<p>\u201cNasci na Col\u00f4nia e por conta da separa\u00e7\u00e3o tive que ir para o Educand\u00e1rio Eunice Weaver, que era para onde iam os filhos de hansenianos internados compulsoriamente nas col\u00f4nias. Meu pai e minha m\u00e3e eram pacientes com sequelas. N\u00f3s \u00e9ramos quatro irm\u00e3os e entre eles uma mulher que minha m\u00e3e doou para ser adotada por um amigo. Os outros tr\u00eas foram encaminhados para o educand\u00e1rio&#8221;, comenta.<\/p>\n<p>Estima-se que cerca de 40 mil crian\u00e7as tenham sido separadas de seus pais, muitas das quais at\u00e9 hoje n\u00e3o reencontraram suas fam\u00edlias. Edmilson explica que na Col\u00f4nia de Marituba, os pacientes eram internados de forma compuls\u00f3ria onde teriam sofrido segrega\u00e7\u00e3o por medida profil\u00e1tica do Governo Federal . A raiz da luta pela causa est\u00e1 na s\u00e9rie de acontecimentos desencadeados pela hansen\u00edase na vida de Pican\u00e7o.<\/p>\n<p>Hoje Edmilson \u00e9 uma grande lideran\u00e7a nos movimentos sociais em Marituba e ainda mora no bairro de Dom Aristides que se originou com o fim das atividades da Col\u00f4nia de Marituba em 1986, ap\u00f3s a visita do Papa Jo\u00e3o Paulo II. A Col\u00f4nia chegou a ter uma popula\u00e7\u00e3o de at\u00e9 900 pessoas vindas de todo o Estado.<\/p>\n<p><strong>O momento politico atual<\/strong> &#8211; Os dados indicam que os incrementos populacionais de Marituba tamb\u00e9m est\u00e3o relacionados a fluxos migrat\u00f3rios, evidenciando a capacidade de reten\u00e7\u00e3o e atra\u00e7\u00e3o populacional do munic\u00edpio.<br \/>\nSegundo os resultados do Censo Demogr\u00e1fico de 2010, aproximadamente 48% da popula\u00e7\u00e3o maritubense \u00e9 natural de outros munic\u00edpios.<\/p>\n<p><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-10-at-13.14.54.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-43879 alignleft\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-10-at-13.14.54-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-10-at-13.14.54-300x200.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-10-at-13.14.54-1024x682.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-10-at-13.14.54.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Patr\u00edcia Mendes nasceu no interior do sert\u00e3o de Pernambuco, em Bodoc\u00f3. Moradora de Marituba h\u00e1 16 anos, Patr\u00edcia come\u00e7ou a empreender vendendo baldes e bacias na feira central de Marituba, numa lona. Cresceu e constru\u00edram as lojas \u201cMundo do Real\u201d e hoje chegam a gerar mais de 120 empregos diretos na loja.<\/p>\n<p>M\u00e3e de tr\u00eas filhos pequenos, Patr\u00edcia come\u00e7ou a ter o desejo de transformar a vida das pessoas para melhor justamente por conta do trabalho nas lojas e do contato com o p\u00fablico, que lhe relatava as dificuldades enfrentadas nos diferentes setores da vida em Marituba. <span style=\"font-family: 'Open Sans', Arial, sans-serif; font-size: 14px;\">Assim nasceu a candidatura vitoriosa nas elei\u00e7\u00f5es municipais de 2020.<\/span><\/p>\n<p>\u201d A hist\u00f3ria de Marituba \u00e9 uma hist\u00f3ria de luta dos trabalhadores que chegaram aqui para trazer desenvolvimento atrav\u00e9s da Estrada de Ferro e que encontraram na \u201cterra dos Umaris\u201d um lar para poder construir sua fam\u00edlia. \u00c9 uma hist\u00f3ria de pessoas que heroicamente lutaram para que fossemos donos de nosso destino pol\u00edtico. Quero honrar a conquista dessas pessoas podendo dar o melhor de mim para construir e para transformar nossa amada cidade em um lugar melhor para nossos filhos e para todos os que aqui habitam\u201d, destacou a prefeita.<\/p>\n<p>Suas principais pautas \u00e0 frente da Prefeitura de Marituba s\u00e3o a mulher, a juventude e a gera\u00e7\u00e3o de emprego e renda.<\/p>\n<p><em>Da Reda\u00e7\u00e3o Comus<\/em><\/p>\n<p><em>Fotos: Vitor Dagort, Ary Brito e divulga\u00e7\u00e3o<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, 21 de abril, Marituba completa 28 anos de emancipa\u00e7\u00e3o pol\u00edtica. Nascida dentro do processo de ocupa\u00e7\u00e3o e de desenvolvimento da regi\u00e3o Amaz\u00f4nica, o munic\u00edpio mant\u00e9m sua tradi\u00e7\u00e3o derivada do amor de seus moradores e vis\u00e3o empreendedora dos diferentes povos que formaram a popula\u00e7\u00e3o do munic\u00edpio. O povoado de Marituba tem origem na Vila Oper\u00e1ria,<\/p>\n","protected":false},"author":25,"featured_media":44820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-44774","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"og:description\" content=\"Hoje, 21 de abril, Marituba completa 28 anos de emancipa\u00e7\u00e3o pol\u00edtica. Nascida dentro do processo de ocupa\u00e7\u00e3o e de desenvolvimento da regi\u00e3o Amaz\u00f4nica, o munic\u00edpio mant\u00e9m sua tradi\u00e7\u00e3o derivada do amor de seus moradores e vis\u00e3o empreendedora dos diferentes povos que formaram a popula\u00e7\u00e3o do munic\u00edpio. O povoado de Marituba tem origem na Vila Oper\u00e1ria,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-21T09:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maritubaimprensa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maritubaimprensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/\"},\"author\":{\"name\":\"maritubaimprensa\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"headline\":\"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico\",\"datePublished\":\"2022-04-21T09:38:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/\"},\"wordCount\":1746,\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/\",\"name\":\"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg\",\"datePublished\":\"2022-04-21T09:38:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg\",\"contentUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg\",\"width\":1000,\"height\":667},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/\",\"name\":\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"description\":\"Site oficial da Prefeitura Municipal de Marituba - PA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\",\"name\":\"maritubaimprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"caption\":\"maritubaimprensa\"},\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/author\\\/maritubaimprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/","og_locale":"pt_BR","og_type":"article","og_title":"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","og_description":"Hoje, 21 de abril, Marituba completa 28 anos de emancipa\u00e7\u00e3o pol\u00edtica. Nascida dentro do processo de ocupa\u00e7\u00e3o e de desenvolvimento da regi\u00e3o Amaz\u00f4nica, o munic\u00edpio mant\u00e9m sua tradi\u00e7\u00e3o derivada do amor de seus moradores e vis\u00e3o empreendedora dos diferentes povos que formaram a popula\u00e7\u00e3o do munic\u00edpio. O povoado de Marituba tem origem na Vila Oper\u00e1ria,","og_url":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/","og_site_name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","article_published_time":"2022-04-21T09:38:47+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg","type":"image\/jpeg"}],"author":"maritubaimprensa","twitter_misc":{"Escrito por":"maritubaimprensa","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/#article","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/"},"author":{"name":"maritubaimprensa","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"headline":"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico","datePublished":"2022-04-21T09:38:47+00:00","mainEntityOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/"},"wordCount":1746,"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/","url":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/","name":"Marituba: forma\u00e7\u00e3o, emancipa\u00e7\u00e3o, crescimento demogr\u00e1fico e atual momento pol\u00edtico - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/#primaryimage"},"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg","datePublished":"2022-04-21T09:38:47+00:00","author":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-formacao-emancipacao-crescimento-demografico-e-atual-momento-politico\/#primaryimage","url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg","contentUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-20-at-13.35.48-e1650472602930.jpeg","width":1000,"height":667},{"@type":"WebSite","@id":"https:\/\/marituba.pa.gov.br\/site\/#website","url":"https:\/\/marituba.pa.gov.br\/site\/","name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","description":"Site oficial da Prefeitura Municipal de Marituba - PA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marituba.pa.gov.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a","name":"maritubaimprensa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","caption":"maritubaimprensa"},"url":"https:\/\/marituba.pa.gov.br\/site\/author\/maritubaimprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/44774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/comments?post=44774"}],"version-history":[{"count":0,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/44774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media\/44820"}],"wp:attachment":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media?parent=44774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/categories?post=44774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/tags?post=44774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}