{"id":44644,"date":"2022-04-08T15:34:27","date_gmt":"2022-04-08T18:34:27","guid":{"rendered":"https:\/\/marituba.pa.gov.br\/site\/?p=44644"},"modified":"2022-04-08T15:34:27","modified_gmt":"2022-04-08T18:34:27","slug":"marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos","status":"publish","type":"post","link":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/","title":{"rendered":"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos"},"content":{"rendered":"<p>A Prefeitura de Marituba, por meio da Secretaria Municipal de Desenvolvimento Econ\u00f4mico, Turismo, Trabalho, Emprego e Renda (Sedeter), realizou na \u00faltima quinta-feira (7) e nesta sexta-feira (8) palestras sobre empreendedorismo voltadas a jovens e adultos. As palestras contam com o apoio do Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae).<\/p>\n<figure id=\"attachment_44645\" aria-describedby=\"caption-attachment-44645\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-44645 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00-300x200.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00-1024x683.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44645\" class=\"wp-caption-text\">Mais de 40 pessoas participaram da palestra Aprenda a Empreender com o Sebrae<\/figcaption><\/figure>\n<p>Com o tema: \u201cAprenda a empreender com o Sebrae\u201d, a Sedeter reuniu, ontem (7), mais de 40 moradores no bairro Almir Gabriel, na Igreja Assembleia de Deus Anapolis, para discutir temas voltados ao empreendedorismo e oportunidades de trabalho.<\/p>\n<p>Durante a palestra, o p\u00fablico recebeu orienta\u00e7\u00f5es sobre as etapas necess\u00e1rias para iniciar um empreendimento, conheceu os cursos de capacita\u00e7\u00f5es dispon\u00edveis pela Sedeter e os cursos em parceria com o governo por meio do projeto Qualifica Par\u00e1. Ao final, o p\u00fablico foi provocado a se tornar empreendedor fomentando a economia do munic\u00edpio.<\/p>\n<figure id=\"attachment_44647\" aria-describedby=\"caption-attachment-44647\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-14.54.53.jpeg\"><img decoding=\"async\" class=\"wp-image-44647 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-14.54.53-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-14.54.53-300x169.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-14.54.53-1024x576.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-14.54.53-1536x864.jpeg 1536w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-14.54.53.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44647\" class=\"wp-caption-text\">Pais e respons\u00e1veis durante a palestra Educa\u00e7\u00e3o Empreendedora<\/figcaption><\/figure>\n<p>J\u00e1 nesta manh\u00e3 (8), a secretaria levou aos pais e respons\u00e1veis de alunos matriculados na escola Dolores Martins uma palestra sobre educa\u00e7\u00e3o empreendedora. A palestra foi comandada pela Educadora Art\u00edstica, H\u00e9len Sanz que tamb\u00e9m \u00e9 monitora do m\u00e9todo NeuroPoint estimulando o aprendizado e criatividade das crian\u00e7as.<\/p>\n<p>\u201cAs crian\u00e7as precisam ser independentes e este olhar para o empreendedorismo \u00e9 algo importante para o crescimento e evolu\u00e7\u00e3o delas. Dificilmente se encontra uma pessoa que tenha esp\u00edrito empreendedor e n\u00e3o tenha postura de autonomia, independ\u00eancia, e capacidade de planejamento. Essas a\u00e7\u00f5es s\u00e3o principais componentes do perfil empreendedor.\u201d, comentou a palestrante H\u00e9len Sanz.<\/p>\n<p>Da Reda\u00e7\u00e3o Comus<\/p>\n<p>Fotos: Vitor Dagort e Matheus Nepomuceno<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Marituba, por meio da Secretaria Municipal de Desenvolvimento Econ\u00f4mico, Turismo, Trabalho, Emprego e Renda (Sedeter), realizou na \u00faltima quinta-feira (7) e nesta sexta-feira (8) palestras sobre empreendedorismo voltadas a jovens e adultos. As palestras contam com o apoio do Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae). Com o tema:<\/p>\n","protected":false},"author":25,"featured_media":44645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-44644","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Marituba, por meio da Secretaria Municipal de Desenvolvimento Econ\u00f4mico, Turismo, Trabalho, Emprego e Renda (Sedeter), realizou na \u00faltima quinta-feira (7) e nesta sexta-feira (8) palestras sobre empreendedorismo voltadas a jovens e adultos. As palestras contam com o apoio do Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae). Com o tema:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T18:34:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maritubaimprensa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maritubaimprensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/\"},\"author\":{\"name\":\"maritubaimprensa\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"headline\":\"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos\",\"datePublished\":\"2022-04-08T18:34:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/\"},\"wordCount\":313,\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/\",\"name\":\"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg\",\"datePublished\":\"2022-04-08T18:34:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg\",\"contentUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg\",\"width\":1500,\"height\":1000},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/\",\"name\":\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"description\":\"Site oficial da Prefeitura Municipal de Marituba - PA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\",\"name\":\"maritubaimprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"caption\":\"maritubaimprensa\"},\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/author\\\/maritubaimprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/","og_locale":"pt_BR","og_type":"article","og_title":"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","og_description":"A Prefeitura de Marituba, por meio da Secretaria Municipal de Desenvolvimento Econ\u00f4mico, Turismo, Trabalho, Emprego e Renda (Sedeter), realizou na \u00faltima quinta-feira (7) e nesta sexta-feira (8) palestras sobre empreendedorismo voltadas a jovens e adultos. As palestras contam com o apoio do Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae). Com o tema:","og_url":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/","og_site_name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","article_published_time":"2022-04-08T18:34:27+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg","type":"image\/jpeg"}],"author":"maritubaimprensa","twitter_misc":{"Escrito por":"maritubaimprensa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/#article","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/"},"author":{"name":"maritubaimprensa","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"headline":"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos","datePublished":"2022-04-08T18:34:27+00:00","mainEntityOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/"},"wordCount":313,"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/","url":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/","name":"Marituba proporciona palestras voltadas ao empreendedorismo \u00e0 jovens e adultos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/#primaryimage"},"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg","datePublished":"2022-04-08T18:34:27+00:00","author":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-proporciona-palestras-voltadas-ao-empreendedorismo-a-jovens-e-adultos\/#primaryimage","url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg","contentUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/04\/WhatsApp-Image-2022-04-08-at-09.50.00.jpeg","width":1500,"height":1000},{"@type":"WebSite","@id":"https:\/\/marituba.pa.gov.br\/site\/#website","url":"https:\/\/marituba.pa.gov.br\/site\/","name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","description":"Site oficial da Prefeitura Municipal de Marituba - PA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marituba.pa.gov.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a","name":"maritubaimprensa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","caption":"maritubaimprensa"},"url":"https:\/\/marituba.pa.gov.br\/site\/author\/maritubaimprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/44644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/comments?post=44644"}],"version-history":[{"count":0,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/44644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media\/44645"}],"wp:attachment":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media?parent=44644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/categories?post=44644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/tags?post=44644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}