{"id":44428,"date":"2022-03-30T17:08:46","date_gmt":"2022-03-30T20:08:46","guid":{"rendered":"https:\/\/marituba.pa.gov.br\/site\/?p=44428"},"modified":"2022-03-30T17:08:46","modified_gmt":"2022-03-30T20:08:46","slug":"governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba","status":"publish","type":"post","link":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/","title":{"rendered":"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba"},"content":{"rendered":"<figure id=\"attachment_44430\" aria-describedby=\"caption-attachment-44430\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.42.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-44430 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.42-300x212.jpeg\" alt=\"\" width=\"300\" height=\"212\" \/><\/a><figcaption id=\"caption-attachment-44430\" class=\"wp-caption-text\">A prefeita Patr\u00edcia Mendes ressaltou a\u00a0 import\u00e2ncia de investir em todo o sistema de seguran\u00e7a<\/figcaption><\/figure>\n<p>A prefeita Patr\u00edcia Mendes participou, na manh\u00e3 desta quarta-feira (30), da assinatura da ordem de servi\u00e7o para in\u00edcio das obras de reforma dos Pres\u00eddios Estaduais Metropolitanos (PEMs) I e II, o que vai determinar o in\u00edcio do processo de erradica\u00e7\u00e3o das pris\u00f5es cont\u00eaineres no estado do Par\u00e1, um avan\u00e7o hist\u00f3rico na garantia de direitos e humaniza\u00e7\u00e3o do tratamento das pessoas privadas de liberdade.<\/p>\n<p>O governador Helder Barbalho e o secret\u00e1rio de Estado de Administra\u00e7\u00e3o Penitenci\u00e1ria, Jarbas Vasconcelos assinaram a OS das obras.<\/p>\n<p>H\u00e9lder Barbalho\u00a0 parabenizou \u00e0 Secretaria de Administra\u00e7\u00e3o Penitenci\u00e1ria (Seap), pela maior transforma\u00e7\u00e3o na hist\u00f3ria da administra\u00e7\u00e3o penitenci\u00e1ria do Par\u00e1.<\/p>\n<p>&#8220;Que n\u00f3s possamos avan\u00e7ar ainda mais, como estamos fazendo hoje. \u00c9 poss\u00edvel transformar o ambiente do c\u00e1rcere em um lugar de promo\u00e7\u00e3o de dignidade e de humanidade em favor dos paraenses\u201d, destacou o governador do Estado.<\/p>\n<p>A prefeita Patr\u00edcia Mendes ressaltou que \u00e9 muito importante o investimento do Governo do Estado em todo o sistema de seguran\u00e7a para trazer condi\u00e7\u00f5es de vida mais segura para toda a popula\u00e7\u00e3o. <span style=\"font-size: 14px;\">\u201cQuero aproveitar o momento para agradecer ao Governador Helder Barbalho por todo o investimento que Marituba tem recebido na Seguran\u00e7a P\u00fablica, desde a parceria na capacita\u00e7\u00e3o e aparelhamento da nossa Guarda Civil Municipal at\u00e9 a inaugura\u00e7\u00e3o da nossa querida Usina da Paz Nova Uni\u00e3o\u201d, destacou Patr\u00edcia Mendes.<\/span><\/p>\n<p>A reforma do Pres\u00eddio Estadual Metropolitano I (PEM I) representa um investimento de R$ 2,8 milh\u00f5es e vai garantir vagas para 591 internos.<\/p>\n<figure id=\"attachment_44431\" aria-describedby=\"caption-attachment-44431\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.46.18.jpeg\"><img decoding=\"async\" class=\"wp-image-44431 size-medium\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.46.18-300x201.jpeg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.46.18-300x201.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.46.18-1024x685.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.46.18.jpeg 1472w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-44431\" class=\"wp-caption-text\">Helder Barbalho, Patr\u00edcia Mendes e Jarbas Vasconcelos em vistoria no Metropiltano.<\/figcaption><\/figure>\n<p>Al\u00e9m disso, a casa penal passar\u00e1 a contar com novas salas de espera para advogados; sala de videomonitoramento; bloco de atendimento de sa\u00fade; bloco de parlat\u00f3rios jur\u00eddicos (compostos por duas salas de v\u00eddeo cust\u00f3dia, uma sala de v\u00eddeo audi\u00eancia, quatro parlat\u00f3rios f\u00edsicos e um parlat\u00f3rio virtual); m\u00f3dulo de ensino com salas de aula, sala de inform\u00e1tica e biblioteca; bloco carcer\u00e1rio com celas coletivas, totalizando 529 vagas; salas de Estado Maior, com sol\u00e1rio pr\u00f3prio, totalizando 14 vagas; celas especiais, com sol\u00e1rio pr\u00f3prio, totalizando onze vagas e galp\u00e3o de trabalho.<\/p>\n<p>J\u00e1 a obra no Pres\u00eddio Estadual Metropolitano II (PEM II) prev\u00ea um investimento de R$ 1,9 milh\u00e3o e vai garantir vagas para 484 internos; al\u00e9m de sala de espera para advogados; sala de videomonitoramento da unidade; bloco de atendimento de sa\u00fade; bloco de parlat\u00f3rios jur\u00eddicos (composto por uma sala de v\u00eddeo cust\u00f3dia, uma sala de v\u00eddeo audi\u00eancia, cinco parlat\u00f3rios f\u00edsicos e um parlat\u00f3rio virtual); m\u00f3dulo de ensino com salas de aula, sala de inform\u00e1tica e biblioteca; bloco carcer\u00e1rio com celas coletivas, totalizando 476 vagas e salas de Estado Maior, com sol\u00e1rio pr\u00f3prio, totalizando oito vagas.<\/p>\n<p>O prazo de execu\u00e7\u00e3o das duas obras ser\u00e1 de um ano e elas culminar\u00e3o com a desativa\u00e7\u00e3o dos cont\u00eaineres que ainda hoje abrigam internos nas duas unidades, os quais ser\u00e3o substitu\u00eddos por m\u00f3dulos carcer\u00e1rios em blocos de concreto. Somados, os investimentos do Governo do Estado nas duas obras chegam a R$ 4,7 milh\u00f5es.<\/p>\n<p><strong>M\u00e3o-de-obra carcer\u00e1ria<\/strong> &#8211; Para a reforma do PEM I e II, a SEAP articulou, junto \u00e0 empresa respons\u00e1vel pelas obras, a contrata\u00e7\u00e3o de 300 internos do sistema penitenci\u00e1rio, que ser\u00e3o remunerados em um sal\u00e1rio m\u00ednimo, al\u00e9m de obterem a remi\u00e7\u00e3o de pena, conforme preconiza a Lei de Execu\u00e7\u00e3o Penal.<\/p>\n<p><em>Da Reda\u00e7\u00e3o Comus com informa\u00e7\u00f5es da Ag\u00eancia Par\u00e1<\/em><\/p>\n<p><em>Fotos: Tchelo Figueiredo <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prefeita Patr\u00edcia Mendes participou, na manh\u00e3 desta quarta-feira (30), da assinatura da ordem de servi\u00e7o para in\u00edcio das obras de reforma dos Pres\u00eddios Estaduais Metropolitanos (PEMs) I e II, o que vai determinar o in\u00edcio do processo de erradica\u00e7\u00e3o das pris\u00f5es cont\u00eaineres no estado do Par\u00e1, um avan\u00e7o hist\u00f3rico na garantia de direitos e<\/p>\n","protected":false},"author":25,"featured_media":44429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-44428","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"og:description\" content=\"A prefeita Patr\u00edcia Mendes participou, na manh\u00e3 desta quarta-feira (30), da assinatura da ordem de servi\u00e7o para in\u00edcio das obras de reforma dos Pres\u00eddios Estaduais Metropolitanos (PEMs) I e II, o que vai determinar o in\u00edcio do processo de erradica\u00e7\u00e3o das pris\u00f5es cont\u00eaineres no estado do Par\u00e1, um avan\u00e7o hist\u00f3rico na garantia de direitos e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T20:08:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maritubaimprensa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maritubaimprensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/\"},\"author\":{\"name\":\"maritubaimprensa\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"headline\":\"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba\",\"datePublished\":\"2022-03-30T20:08:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/\"},\"wordCount\":678,\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/\",\"name\":\"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg\",\"datePublished\":\"2022-03-30T20:08:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg\",\"contentUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg\",\"width\":1000,\"height\":668},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/\",\"name\":\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"description\":\"Site oficial da Prefeitura Municipal de Marituba - PA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\",\"name\":\"maritubaimprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"caption\":\"maritubaimprensa\"},\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/author\\\/maritubaimprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","og_description":"A prefeita Patr\u00edcia Mendes participou, na manh\u00e3 desta quarta-feira (30), da assinatura da ordem de servi\u00e7o para in\u00edcio das obras de reforma dos Pres\u00eddios Estaduais Metropolitanos (PEMs) I e II, o que vai determinar o in\u00edcio do processo de erradica\u00e7\u00e3o das pris\u00f5es cont\u00eaineres no estado do Par\u00e1, um avan\u00e7o hist\u00f3rico na garantia de direitos e","og_url":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/","og_site_name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","article_published_time":"2022-03-30T20:08:46+00:00","og_image":[{"width":1000,"height":668,"url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg","type":"image\/jpeg"}],"author":"maritubaimprensa","twitter_misc":{"Escrito por":"maritubaimprensa","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/#article","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/"},"author":{"name":"maritubaimprensa","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"headline":"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba","datePublished":"2022-03-30T20:08:46+00:00","mainEntityOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/"},"wordCount":678,"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/","url":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/","name":"Governo do Estado assina ordem de servi\u00e7o para obras de pres\u00eddios em Marituba - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/#primaryimage"},"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg","datePublished":"2022-03-30T20:08:46+00:00","author":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marituba.pa.gov.br\/site\/governo-do-estado-assina-ordem-de-servico-para-obras-de-presidios-em-marituba\/#primaryimage","url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg","contentUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-30-at-13.48.45-e1648659783417.jpeg","width":1000,"height":668},{"@type":"WebSite","@id":"https:\/\/marituba.pa.gov.br\/site\/#website","url":"https:\/\/marituba.pa.gov.br\/site\/","name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","description":"Site oficial da Prefeitura Municipal de Marituba - PA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marituba.pa.gov.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a","name":"maritubaimprensa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","caption":"maritubaimprensa"},"url":"https:\/\/marituba.pa.gov.br\/site\/author\/maritubaimprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/44428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/comments?post=44428"}],"version-history":[{"count":0,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/44428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media\/44429"}],"wp:attachment":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media?parent=44428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/categories?post=44428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/tags?post=44428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}