{"id":42434,"date":"2022-02-02T16:11:53","date_gmt":"2022-02-02T19:11:53","guid":{"rendered":"https:\/\/marituba.pa.gov.br\/site\/?p=42434"},"modified":"2022-02-02T16:11:53","modified_gmt":"2022-02-02T19:11:53","slug":"semel-retoma-atividades-de-esportes-nesta-quarta-feira","status":"publish","type":"post","link":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/","title":{"rendered":"Semel retoma atividades de esportes nesta quarta-feira"},"content":{"rendered":"<div id=\":rg\" class=\"Ar Au Ao\">\n<div id=\":rc\" class=\"Am Al editable LW-avf tS-tW tS-tY\" tabindex=\"1\" role=\"textbox\" contenteditable=\"true\" spellcheck=\"false\" aria-label=\"Corpo da mensagem\" aria-multiline=\"true\">\n<figure id=\"attachment_42453\" aria-describedby=\"caption-attachment-42453\" style=\"width: 702px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5823-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-42453 size-large\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5823-1024x681.jpg\" alt=\"\" width=\"702\" height=\"467\" \/><\/a><figcaption id=\"caption-attachment-42453\" class=\"wp-caption-text\">Turma Sa\u00fade na Terceira Idade<\/figcaption><\/figure>\n<p>Retornando com as atividades e projetos de esporte em Marituba, a Secretaria Municipal de Esporte e Lazer (SEMEL), realizou nesta manh\u00e3 (02) uma a\u00e7\u00e3o que reuniu os grupos de atividades de boxe, futsal, e karate e Sa\u00fade na terceira da secretaria para o regresso das atividades.<\/p>\n<p>\u201cPor enquanto todos os nossos esportes funcionam no espa\u00e7o do Gin\u00e1sio Poliesportivo de Marituba, mas a ideia \u00e9 que esse projeto se expanda \u00e0s comunidades do munic\u00edpio\u201d, explica o secret\u00e1rio da Semel R\u00e9gis Souza.<\/p>\n<figure id=\"attachment_42442\" aria-describedby=\"caption-attachment-42442\" style=\"width: 203px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled.jpg\"><img decoding=\"async\" class=\"wp-image-42442\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled-e1643829018192-300x221.jpg\" alt=\"\" width=\"203\" height=\"149\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled-e1643829018192-300x221.jpg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled-e1643829018192-1024x755.jpg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled-e1643829018192-1536x1133.jpg 1536w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled-e1643829018192-768x566.jpg 768w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5784-scaled-e1643829018192.jpg 1836w\" sizes=\"(max-width: 203px) 100vw, 203px\" \/><\/a><figcaption id=\"caption-attachment-42442\" class=\"wp-caption-text\">Zenaide Barbosa<\/figcaption><\/figure>\n<p><strong>Sa\u00fade na Terceira Idade<\/strong> \u2013 A aposentada Zeneide Barbosa, 69 anos, \u00e9 uma das participantes do projeto Sa\u00fade na Terceira Idade que oferece dan\u00e7a terap\u00eautica e atividades f\u00edsicas aos idosos toda segunda, quarta e sexta-feira. \u201cEssas atividades s\u00e3o \u00f3timas para mim porque aqui no meio dos meus colegas tenho alegria e carinho por todos, me sinto no meio de uma fam\u00edlia. Aqui gosto de dan\u00e7ar Carimb\u00f3, Quadrilha e de me exercitar\u201d, afirma.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_42455\" aria-describedby=\"caption-attachment-42455\" style=\"width: 234px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5827-scaled-e1643828375711.jpg\"><img decoding=\"async\" class=\"wp-image-42455\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5827-300x200.jpg\" alt=\"\" width=\"234\" height=\"156\" \/><\/a><figcaption id=\"caption-attachment-42455\" class=\"wp-caption-text\">Turma de Karate<\/figcaption><\/figure>\n<p><strong>Karate \u2013 <\/strong>Todas as ter\u00e7a e quintas-feiras, a Semel leva o projeto de Karate com turmas de alunos com idade a partir dos 4 anos. \u201cO Karate ensina a pessoa a como a se integrar em sociedade. Temos casos de pessoas que eram totalmente sedent\u00e1rias e hoje s\u00e3o ativas por meio do esporte\u201d, explica o professor de Karate, Ant\u00f4nio Leite Jr.<\/p>\n<p>\u201cAqui, em Marituba, a gente j\u00e1 formou 32 faixas pretas. Temos ainda campe\u00f5es mundiais, brasileiros, intercontinentais e tenho a honra de poder falar que Marituba vai representar o nosso Estado no Campeonato Mundial de Karate que ir\u00e1 acontecer em junho, na Servia\u201d, afirma o professor que atua no munic\u00edpio h\u00e1 12 anos.<\/p>\n<figure id=\"attachment_42456\" aria-describedby=\"caption-attachment-42456\" style=\"width: 249px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5829-scaled-e1643828428107.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42456 \" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5829-300x200.jpg\" alt=\"\" width=\"249\" height=\"166\" \/><\/a><figcaption id=\"caption-attachment-42456\" class=\"wp-caption-text\">Turma de boxe. Aluno Jorge Amorin a direita<\/figcaption><\/figure>\n<p><strong>Boxe<\/strong> \u2013 A turma de boxe re\u00fane pessoas de todas as idades, trazendo v\u00e1rios benef\u00edcios \u00e0 sa\u00fade com a pr\u00e1tica do esporte e tirando jovens da ociosidade. \u201cPor meio do esporte a gente est\u00e1 resgatando crian\u00e7as e jovens, levando-os a competi\u00e7\u00f5es e fazendo com que tenham intera\u00e7\u00e3o entre eles. \u00c9 um prazer e uma alegria imensa levar esses alunos para competi\u00e7\u00f5es e quem sabe revelar grandes talentos\u201d, disse o professor de boxe Reginaldo Dias.<\/p>\n<p>O jovem Jorge Amorim, 12 anos, encontrou no boxe a sua realiza\u00e7\u00e3o. \u201cEu comecei a lutar artes marciais desde os 8 anos de idade e no \u00faltimo ano encontrei o boxe que \u00e9 um esporte que quero dar continuidade na minha vida. Em abril vou participar do meu segundo campeonato e \u00e9 uma sensa\u00e7\u00e3o de muita alegria participar do esporte seja ganhando ou perdendo\u201d, afirma.<\/p>\n<figure id=\"attachment_42458\" aria-describedby=\"caption-attachment-42458\" style=\"width: 257px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5837-scaled-e1643828412335.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-42458 \" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5837-300x200.jpg\" alt=\"\" width=\"257\" height=\"171\" \/><\/a><figcaption id=\"caption-attachment-42458\" class=\"wp-caption-text\">Categoria de 08 aos 13 anos de futsal<\/figcaption><\/figure>\n<p><strong>Futsal \u2013 <\/strong>A Semel oferece ainda turmas de futsal, todas as ter\u00e7as e sextas-feiras formando duas categorias com turmas masculinas (de 08 aos 13 anos e de 14 aos 16 anos), al\u00e9m de uma turma feminina.<\/p>\n<p>Quem quiser participar de qualquer projeto da Semel deve ir at\u00e9 a Secretaria de Esporte e Lazer e apresentar seus documentos pessoais com foto para a matr\u00edcula. Para aqueles jovens que est\u00e3o em idade escolar \u00e9 necess\u00e1rio trazer um documento que comprove o grau de escolaridade do aluno.<\/p>\n<p>Da Reda\u00e7\u00e3o Comus<\/p>\n<p>Fotos: Fotos Ary Brito<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retornando com as atividades e projetos de esporte em Marituba, a Secretaria Municipal de Esporte e Lazer (SEMEL), realizou nesta manh\u00e3 (02) uma a\u00e7\u00e3o que reuniu os grupos de atividades de boxe, futsal, e karate e Sa\u00fade na terceira da secretaria para o regresso das atividades. \u201cPor enquanto todos os nossos esportes funcionam no espa\u00e7o<\/p>\n","protected":false},"author":25,"featured_media":42450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-42434","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semel retoma atividades de esportes nesta quarta-feira - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semel retoma atividades de esportes nesta quarta-feira - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"og:description\" content=\"Retornando com as atividades e projetos de esporte em Marituba, a Secretaria Municipal de Esporte e Lazer (SEMEL), realizou nesta manh\u00e3 (02) uma a\u00e7\u00e3o que reuniu os grupos de atividades de boxe, futsal, e karate e Sa\u00fade na terceira da secretaria para o regresso das atividades. \u201cPor enquanto todos os nossos esportes funcionam no espa\u00e7o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T19:11:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5814-scaled-e1643828508452.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maritubaimprensa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maritubaimprensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/\"},\"author\":{\"name\":\"maritubaimprensa\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"headline\":\"Semel retoma atividades de esportes nesta quarta-feira\",\"datePublished\":\"2022-02-02T19:11:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/\"},\"wordCount\":579,\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_5814-scaled-e1643828508452.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/\",\"name\":\"Semel retoma atividades de esportes nesta quarta-feira - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_5814-scaled-e1643828508452.jpg\",\"datePublished\":\"2022-02-02T19:11:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_5814-scaled-e1643828508452.jpg\",\"contentUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/IMG_5814-scaled-e1643828508452.jpg\",\"width\":1000,\"height\":665},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/\",\"name\":\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"description\":\"Site oficial da Prefeitura Municipal de Marituba - PA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\",\"name\":\"maritubaimprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"caption\":\"maritubaimprensa\"},\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/author\\\/maritubaimprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semel retoma atividades de esportes nesta quarta-feira - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/","og_locale":"pt_BR","og_type":"article","og_title":"Semel retoma atividades de esportes nesta quarta-feira - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","og_description":"Retornando com as atividades e projetos de esporte em Marituba, a Secretaria Municipal de Esporte e Lazer (SEMEL), realizou nesta manh\u00e3 (02) uma a\u00e7\u00e3o que reuniu os grupos de atividades de boxe, futsal, e karate e Sa\u00fade na terceira da secretaria para o regresso das atividades. \u201cPor enquanto todos os nossos esportes funcionam no espa\u00e7o","og_url":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/","og_site_name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","article_published_time":"2022-02-02T19:11:53+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5814-scaled-e1643828508452.jpg","type":"image\/jpeg"}],"author":"maritubaimprensa","twitter_misc":{"Escrito por":"maritubaimprensa","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/#article","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/"},"author":{"name":"maritubaimprensa","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"headline":"Semel retoma atividades de esportes nesta quarta-feira","datePublished":"2022-02-02T19:11:53+00:00","mainEntityOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/"},"wordCount":579,"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5814-scaled-e1643828508452.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/","url":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/","name":"Semel retoma atividades de esportes nesta quarta-feira - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/#primaryimage"},"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5814-scaled-e1643828508452.jpg","datePublished":"2022-02-02T19:11:53+00:00","author":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marituba.pa.gov.br\/site\/semel-retoma-atividades-de-esportes-nesta-quarta-feira\/#primaryimage","url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5814-scaled-e1643828508452.jpg","contentUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/02\/IMG_5814-scaled-e1643828508452.jpg","width":1000,"height":665},{"@type":"WebSite","@id":"https:\/\/marituba.pa.gov.br\/site\/#website","url":"https:\/\/marituba.pa.gov.br\/site\/","name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","description":"Site oficial da Prefeitura Municipal de Marituba - PA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marituba.pa.gov.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a","name":"maritubaimprensa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","caption":"maritubaimprensa"},"url":"https:\/\/marituba.pa.gov.br\/site\/author\/maritubaimprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/42434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/comments?post=42434"}],"version-history":[{"count":0,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/42434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media\/42450"}],"wp:attachment":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media?parent=42434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/categories?post=42434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/tags?post=42434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}