{"id":41991,"date":"2022-01-23T17:07:35","date_gmt":"2022-01-23T20:07:35","guid":{"rendered":"https:\/\/marituba.pa.gov.br\/site\/?p=41991"},"modified":"2022-01-23T17:07:35","modified_gmt":"2022-01-23T20:07:35","slug":"marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos","status":"publish","type":"post","link":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/","title":{"rendered":"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos"},"content":{"rendered":"<figure id=\"attachment_41992\" aria-describedby=\"caption-attachment-41992\" style=\"width: 702px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.36.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-41992 size-large\" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.36-1024x682.jpeg\" alt=\"\" width=\"702\" height=\"468\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.36-1024x682.jpeg 1024w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.36-300x200.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.36.jpeg 1280w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/a><figcaption id=\"caption-attachment-41992\" class=\"wp-caption-text\">Todas as crian\u00e7as imunizadas no munic\u00edpio recebem um certificado de coragem<\/figcaption><\/figure>\n<p>A partir desta semana, o munic\u00edpio de Marituba passa a imunizar contra a Covid-19 crian\u00e7as com idade entre 5 e 11 anos sem comorbidade. O munic\u00edpio seguir\u00e1 ainda vacinando crian\u00e7as da mesma faixa et\u00e1ria que possuem comorbidade. Todas as crian\u00e7as imunizadas contra o coronav\u00edrus no munic\u00edpio recebem um certificado de coragem, uma forma l\u00fadica de parabeniz\u00e1-las pela coragem e bravura de receber o imunizante.<\/p>\n<p>A vacina\u00e7\u00e3o em crian\u00e7as acontece de 8h \u00e0s 14h, no CER III \u2013 BR 316, KM 12, ao lado do Gin\u00e1sio Poliesportivo de Marituba. Para se vacinar \u00e9 necess\u00e1rio que a crian\u00e7a esteja acompanhada de um adulto respons\u00e1vel e apresente os seguintes documentos: CPF, Cart\u00e3o SUS, comprovante de resid\u00eancia, carteira de vacina\u00e7\u00e3o e laudo m\u00e9dico em caso de comorbidade.<\/p>\n<figure id=\"attachment_41996\" aria-describedby=\"caption-attachment-41996\" style=\"width: 255px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.33.jpeg\"><img decoding=\"async\" class=\"wp-image-41996 \" src=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.33-e1642968437836-300x232.jpeg\" alt=\"\" width=\"255\" height=\"197\" srcset=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.33-e1642968437836-300x232.jpeg 300w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.33-e1642968437836-768x593.jpeg 768w, https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.33-e1642968437836.jpeg 912w\" sizes=\"(max-width: 255px) 100vw, 255px\" \/><\/a><figcaption id=\"caption-attachment-41996\" class=\"wp-caption-text\">Andreia Queiroz e o filho Andr\u00e9 Luiz Queiroz<\/figcaption><\/figure>\n<p>A dona de casa Andreia Queiroz, 36 anos , levou seu filho Andr\u00e9 Luiz Queiroz, 11 anos, ao CER para receber o imunizante. Ela conta que Luiz possui problema renal e por isso o cuidado com a sa\u00fade dele \u00e9 redobrado. \u201cEu estava ansiosa para a chegada da vacina\u00e7\u00e3o contra a Covid-19 para o meu filho. Na minha casa todos se vacinaram e eu jamais iria deixar de imuniz\u00e1-lo tamb\u00e9m. A gente tem que acreditar na ci\u00eancia e eu estou muito feliz por esse dia\u201d, disse.<\/p>\n<p>\u201c\u00c9 muito importante que a gente imunize contra a Covid-19 as nossas crian\u00e7as para que a gente atinja 100% da nossa popula\u00e7\u00e3o com essa vacina e consiga conter o cont\u00e1gio desta doen\u00e7a\u201d, pontua o secret\u00e1rio de sa\u00fade Alexandre Cardoso.<\/p>\n<p>Marituba segue ainda com a vacina\u00e7\u00e3o contra o coronav\u00edrus em pessoas com idade acima dos 12 anos em v\u00e1rios pontos do munic\u00edpio. Recebem a primeira dose pessoas com idade a partir dos 12 anos completos; a segunda dose ser\u00e1 aplicada naqueles que receberam a primeira dose at\u00e9 o dia 27 de dezembro. J\u00e1 a terceira dose \u00e9 aplicada em pessoas maiores de 18 anos e com quatro meses da aplica\u00e7\u00e3o da segunda dose.<\/p>\n<p>Pessoas que estejam imunossuprimidas recebem a terceira dose 28 dias ap\u00f3s a aplica\u00e7\u00e3o da segunda dose. Esse grupo recebe ainda a quarta dose da vacina quatro meses ap\u00f3s a terceira dose.<\/p>\n<p>Para se vacinar \u00e9 importante apresentar os seguintes documentos: RG, CPF, Cart\u00e3o SUS, Carteirinha de Vacina\u00e7\u00e3o e comprovante de resid\u00eancia de Marituba.<\/p>\n<blockquote><p>CRONOGRAMA<\/p>\n<p><strong>Segunda-feira (24) a S\u00e1bado (29)<\/strong><\/p>\n<p>Primeira dose: para crian\u00e7as de 5 a 11 anos com ou sem comorbidade.<\/p>\n<ul>\n<li>Centro Especializado em Reabilita\u00e7\u00e3o (CER III) \u2013 Br 316, KM 12 \u2013 ao lado do Gin\u00e1sio Poliesportivo de Marituba.<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: das 8h \u00e0s 22h<\/em><\/p>\n<p><strong>Segunda-feira (24) a S\u00e1bado (29)<\/strong><\/p>\n<p><strong>Primeira dose:<\/strong> para pessoas com idade a partir dos 12 anos completos;<\/p>\n<p><strong>Segunda dose:<\/strong> para quem recebeu a primeira dose at\u00e9 o dia 27 de dezembro de 2021;<\/p>\n<p><strong>Terceira dose ou dose de refor\u00e7o:<\/strong> para pessoas com idade a partir dos 18 anos completos e com quatro meses da aplica\u00e7\u00e3o da segunda dose.<\/p>\n<p><strong>Terceira dose ou dose adicional para imunocomprometidos:<\/strong> para pessoas que estejam imunocomprometidas com 28 dias da aplica\u00e7\u00e3o da segunda dose.<\/p>\n<p><strong>Quarta dose:<\/strong> para todos os indiv\u00edduos imunocomprometidos acima de 18 anos de idade quatro meses ap\u00f3s a terceira dose.<\/p>\n<ul>\n<li>Centro Especializado em Reabilita\u00e7\u00e3o (CER III) \u2013 Br 316, KM 12 \u2013 ao lado do Gin\u00e1sio Poliesportivo de Marituba.<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: de 08h \u00e0s 22h<\/em><\/p>\n<ul>\n<li>USF Haifa Gabriel (Rua Ant\u00f4nio Armando S\/N. Bairro Almir Gabriel)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 13h \u00e0s 16h<\/em><\/p>\n<ul>\n<li>UBS Gilson Rufino Gon\u00e7alves (Tv. Ant\u00f4nio Maria Brito, 10 \u2013 Bairro Decouville)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 7h \u00e0s 16h<\/em><\/p>\n<ul>\n<li>USF Jos\u00e9 Coelho Serr\u00e3o (Rua Da Sagre S\/N. Bairro Boa Vista)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 13h \u00e0s 16h<\/em><\/p>\n<ul>\n<li>USF Nova Marituba (Loteamento Imperial S\/N. Bairro Nova Marituba)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 9h \u00e0s 15h30<\/em><\/p>\n<ul>\n<li>USF Adal\u00facio Calado (Pra\u00e7a Jarbas Passarinho S\/N. Bairro Dom Aristides)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 13h \u00e0s 16h<\/em><\/p>\n<ul>\n<li>UBS Nossa Senhora da Paz (Rua Da Divisa S\/N. Bairro Nossa Sra. Da Paz)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 08h \u00e0s 16h<\/em><\/p>\n<ul>\n<li>USF Uni\u00e3o (Rua S\u00e3o Francisco S\/N. Bairro Uni\u00e3o)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 13h \u00e0s 16h<\/em><\/p>\n<ul>\n<li>USF Manoel Paiva (TV. Oitava, QD. 08, n\u00ba 13 &#8211; Agrovila S\u00e3o Pedro)<\/li>\n<\/ul>\n<p><em>Hor\u00e1rio: 10h \u00e0s 16h<\/em><\/p>\n<p>Observa\u00e7\u00e3o: Na sexta-feira n\u00e3o haver\u00e1 vacina\u00e7\u00e3o contra Covid-19 na USF Jos\u00e9 Coelho Serr\u00e3o.<\/p><\/blockquote>\n<p>Da Reda\u00e7\u00e3o Comus<\/p>\n<p>Fotos: Patrik Santos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir desta semana, o munic\u00edpio de Marituba passa a imunizar contra a Covid-19 crian\u00e7as com idade entre 5 e 11 anos sem comorbidade. O munic\u00edpio seguir\u00e1 ainda vacinando crian\u00e7as da mesma faixa et\u00e1ria que possuem comorbidade. Todas as crian\u00e7as imunizadas contra o coronav\u00edrus no munic\u00edpio recebem um certificado de coragem, uma forma l\u00fadica de<\/p>\n","protected":false},"author":25,"featured_media":41993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-41991","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"og:description\" content=\"A partir desta semana, o munic\u00edpio de Marituba passa a imunizar contra a Covid-19 crian\u00e7as com idade entre 5 e 11 anos sem comorbidade. O munic\u00edpio seguir\u00e1 ainda vacinando crian\u00e7as da mesma faixa et\u00e1ria que possuem comorbidade. Todas as crian\u00e7as imunizadas contra o coronav\u00edrus no munic\u00edpio recebem um certificado de coragem, uma forma l\u00fadica de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-23T20:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maritubaimprensa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maritubaimprensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/\"},\"author\":{\"name\":\"maritubaimprensa\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"headline\":\"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos\",\"datePublished\":\"2022-01-23T20:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/\"},\"wordCount\":764,\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/\",\"name\":\"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg\",\"datePublished\":\"2022-01-23T20:07:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/\",\"name\":\"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028\",\"description\":\"Site oficial da Prefeitura Municipal de Marituba - PA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/#\\\/schema\\\/person\\\/01641c6b91674b43ef06391daf008b4a\",\"name\":\"maritubaimprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g\",\"caption\":\"maritubaimprensa\"},\"url\":\"https:\\\/\\\/marituba.pa.gov.br\\\/site\\\/author\\\/maritubaimprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","og_description":"A partir desta semana, o munic\u00edpio de Marituba passa a imunizar contra a Covid-19 crian\u00e7as com idade entre 5 e 11 anos sem comorbidade. O munic\u00edpio seguir\u00e1 ainda vacinando crian\u00e7as da mesma faixa et\u00e1ria que possuem comorbidade. Todas as crian\u00e7as imunizadas contra o coronav\u00edrus no munic\u00edpio recebem um certificado de coragem, uma forma l\u00fadica de","og_url":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/","og_site_name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","article_published_time":"2022-01-23T20:07:35+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg","type":"image\/jpeg"}],"author":"maritubaimprensa","twitter_misc":{"Escrito por":"maritubaimprensa","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/#article","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/"},"author":{"name":"maritubaimprensa","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"headline":"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos","datePublished":"2022-01-23T20:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/"},"wordCount":764,"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/","url":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/","name":"Marituba vacina crian\u00e7as sem comorbidade com idade entre 5 e 11 anos - Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","isPartOf":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/#primaryimage"},"image":{"@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg","datePublished":"2022-01-23T20:07:35+00:00","author":{"@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marituba.pa.gov.br\/site\/marituba-vacina-criancas-sem-comorbidade-com-idade-entre-5-e-11-anos\/#primaryimage","url":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg","contentUrl":"https:\/\/marituba.pa.gov.br\/site\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-21-at-21.24.35-1.jpeg","width":1280,"height":853},{"@type":"WebSite","@id":"https:\/\/marituba.pa.gov.br\/site\/#website","url":"https:\/\/marituba.pa.gov.br\/site\/","name":"Prefeitura Municipal de Marituba - PA | Gest\u00e3o 2025-2028","description":"Site oficial da Prefeitura Municipal de Marituba - PA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marituba.pa.gov.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marituba.pa.gov.br\/site\/#\/schema\/person\/01641c6b91674b43ef06391daf008b4a","name":"maritubaimprensa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/757413b4d5eb4de3d532c20c347bada8f146eea4fc591b2e238b914a23a2b51b?s=96&d=mm&r=g","caption":"maritubaimprensa"},"url":"https:\/\/marituba.pa.gov.br\/site\/author\/maritubaimprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/41991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/comments?post=41991"}],"version-history":[{"count":0,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/posts\/41991\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media\/41993"}],"wp:attachment":[{"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/media?parent=41991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/categories?post=41991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marituba.pa.gov.br\/site\/wp-json\/wp\/v2\/tags?post=41991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}